{"id":14536,"date":"2026-02-26T04:37:48","date_gmt":"2026-02-26T03:37:48","guid":{"rendered":"https:\/\/rowermax.shop\/ro64\/produkt\/rower-gorski-kross-hexagon-1-0-26-xs14-niebieski-srebrny-polysk\/"},"modified":"2026-02-26T04:37:48","modified_gmt":"2026-02-26T03:37:48","slug":"rower-gorski-kross-hexagon-1-0-26-xs14-niebieski-srebrny-polysk","status":"publish","type":"product","link":"https:\/\/kelzavo.shop\/ro64\/produkt\/rower-gorski-kross-hexagon-1-0-26-xs14-niebieski-srebrny-polysk\/","title":{"rendered":"Rower g\u00f3rski Kross Hexagon 1.0 26 XS(14&quot;) niebieski\/srebrny po\u0142ysk"},"content":{"rendered":"<div style=\"font-family: Arial, sans-serif; line-height: 1.6; color: #333; padding: 20px; clear: both; display: block; width: 100%; float: none; position: static; overflow: hidden;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2560px;max-height:462px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/116bff\/da47a53c4dc1804c776729e60d8d\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Marka-Kross\" srcset=\"https:\/\/a.allegroimg.com\/original\/116bff\/da47a53c4dc1804c776729e60d8d\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Marka-Kross 360w,https:\/\/a.allegroimg.com\/original\/116bff\/da47a53c4dc1804c776729e60d8d\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Marka-Kross 720w,https:\/\/a.allegroimg.com\/original\/116bff\/da47a53c4dc1804c776729e60d8d\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Marka-Kross 1024w,https:\/\/a.allegroimg.com\/original\/116bff\/da47a53c4dc1804c776729e60d8d\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Marka-Kross 1440w,https:\/\/a.allegroimg.com\/original\/116bff\/da47a53c4dc1804c776729e60d8d\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Marka-Kross 2560w\" sizes=\"100vw\" width=\"2560px\" alt=\"Rower g\u00f3rski Kross Hexagon 1.0 26 XS(14&amp;quot;) niebieski\/srebrny po\u0142ysk Marka Kross\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h1>Rower g\u00f3rski Kross Hexagon 1.0 26 XS(14&#8243;) niebieski\/srebrny po\u0142ysk<\/h1>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:886px;max-height:552px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk\" srcset=\"https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk 360w,https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk 720w,https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk 886w,https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk 886w\" sizes=\"100vw\" width=\"886px\" alt=\"Rower g\u00f3rski Kross Hexagon 1.0 26 XS(14&amp;quot;) niebieski\/srebrny po\u0142ysk\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2560px;max-height:462px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/116bff\/da47a53c4dc1804c776729e60d8d\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Marka-Kross\" srcset=\"https:\/\/a.allegroimg.com\/original\/116bff\/da47a53c4dc1804c776729e60d8d\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Marka-Kross 360w,https:\/\/a.allegroimg.com\/original\/116bff\/da47a53c4dc1804c776729e60d8d\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Marka-Kross 720w,https:\/\/a.allegroimg.com\/original\/116bff\/da47a53c4dc1804c776729e60d8d\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Marka-Kross 1024w,https:\/\/a.allegroimg.com\/original\/116bff\/da47a53c4dc1804c776729e60d8d\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Marka-Kross 1440w,https:\/\/a.allegroimg.com\/original\/116bff\/da47a53c4dc1804c776729e60d8d\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Marka-Kross 2560w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"2560px\" alt=\"Rower g\u00f3rski Kross Hexagon 1.0 26 XS(14&amp;quot;) niebieski\/srebrny po\u0142ysk Marka Kross\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\"><b>\u2705 Kross<\/b> jest liderem sprzeda\u017cy rower\u00f3w w Polsce. <b>W sezonie 2022 sprzeda\u017c rower\u00f3w wzros\u0142a a\u017c o 21%.<\/b> Cechuje go pe\u0142en profesjonalizm i wysoka jako\u015b\u0107 wykonania. <b>Kross<\/b> w swojej kolekcji posiada rowery do r\u00f3\u017cnych zastosowa\u0144: g\u00f3rskich, szosowych, elektrycznych, turystycznych, miejskich i dzieci\u0119cych.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\"><b>\u2705 SHIMANO<\/b> jest najwi\u0119ksz\u0105 na \u015bwiecie firm\u0105 produkuj\u0105c\u0105 cz\u0119\u015bci rowerowe. To najbardziej znana i ceniona marka na rynku, a jej komponenty s\u0105 wykorzystywane w wi\u0119kszo\u015bci rower\u00f3w.<\/p>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2560px;max-height:456px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11c343\/3eac7a494e3e8e7c61c4cc23558e\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Model-Hexagon-1-0\" srcset=\"https:\/\/a.allegroimg.com\/original\/11c343\/3eac7a494e3e8e7c61c4cc23558e\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Model-Hexagon-1-0 360w,https:\/\/a.allegroimg.com\/original\/11c343\/3eac7a494e3e8e7c61c4cc23558e\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Model-Hexagon-1-0 720w,https:\/\/a.allegroimg.com\/original\/11c343\/3eac7a494e3e8e7c61c4cc23558e\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Model-Hexagon-1-0 1024w,https:\/\/a.allegroimg.com\/original\/11c343\/3eac7a494e3e8e7c61c4cc23558e\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Model-Hexagon-1-0 1440w,https:\/\/a.allegroimg.com\/original\/11c343\/3eac7a494e3e8e7c61c4cc23558e\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Model-Hexagon-1-0 2560w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"2560px\" alt=\"Rower g\u00f3rski Kross Hexagon 1.0 26 XS(14&amp;quot;) niebieski\/srebrny po\u0142ysk Model Hexagon 1.0\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">\u2139\ufe0f SUGEROWANY WZROST: 145-157<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">\u2705 Ka\u017cdy z nas chce czasem wyjecha\u0107 z miasta i odpocz\u0105\u0107 w lesie z dala od cywilizacji. Albo rzuci\u0107 to wszystko i wyjecha\u0107 w Bieszczady. Nie warto pozwoli\u0107, \u017ceby w takich sytuacjach ogranicza\u0142 nas rower. Dla wszystkich, kt\u00f3rzy ceni\u0105 sobie uniwersalno\u015b\u0107 w przyst\u0119pnej cenie powsta\u0142 <b>KROSS Hexagon 1.0<\/b>. To bud\u017cetowy rower miejski z mo\u017cliwo\u015bci\u0105 zamontowania szerszej, terenowej opony. <b>Wygodna geometria<\/b> pozwala przyj\u0105\u0107 zrelaksowan\u0105, u\u0142atwiaj\u0105c\u0105 obserwacj\u0119 otoczenia, pozycj\u0119 za kierownic\u0105.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:394px;max-height:174px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11fd45\/68c90a4e47cba270993fd03460a2\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Stopien-zlozenia-do-samodzielnego-zlozenia-do-regulacji\" srcset=\"https:\/\/a.allegroimg.com\/original\/11fd45\/68c90a4e47cba270993fd03460a2\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Stopien-zlozenia-do-samodzielnego-zlozenia-do-regulacji 360w,https:\/\/a.allegroimg.com\/original\/11fd45\/68c90a4e47cba270993fd03460a2\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Stopien-zlozenia-do-samodzielnego-zlozenia-do-regulacji 394w,https:\/\/a.allegroimg.com\/original\/11fd45\/68c90a4e47cba270993fd03460a2\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Stopien-zlozenia-do-samodzielnego-zlozenia-do-regulacji 394w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"394px\" alt=\"Rower g\u00f3rski Kross Hexagon 1.0 26 XS(14&amp;quot;) niebieski\/srebrny po\u0142ysk Stopie\u0144 z\u0142o\u017cenia do samodzielnego z\u0142o\u017cenia, do regulacji\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">\u2705 <b>KROSS Hexagon 1.0&nbsp; t<\/b>o nie tylko <b>nowy lakier po\u0142o\u017cony na ramie<\/b> \u2013 poprawili\u015bmy wiele drobnych detali, kt\u00f3re przek\u0142adaj\u0105 si\u0119 na przyjemno\u015b\u0107 oraz komfort p\u0142yn\u0105ce z jazdy.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">\u2705 <b>KROSS Hexagon 1.0 <\/b>to sprawdzony <b>osprz\u0119t Shimano zapewniaj\u0105cy Ci 21 prze\u0142o\u017ce\u0144<\/b>. Jest on niezwykle prosty w serwisowaniu oraz tani w eksploatacji. Za bezpieczne hamowanie odpowiadaj\u0105 <b>hamulce typu v-brake<\/b>, gwarantuj\u0105 wystarczaj\u0105co du\u017c\u0105 si\u0142\u0119 hamowania, kt\u00f3ra bezpiecznie zatrzyma Ci\u0119 w ka\u017cdych warunkach. Nasza propozycja rekreacyjnego roweru g\u00f3rskiego posiada tak\u017ce <b>amortyzowany widelec <\/b>u\u0142atwiaj\u0105cy jazd\u0119 po wszelkiego rodzaju nier\u00f3wno\u015bciach oraz pokonywanie drobnych przeszk\u00f3d terenowych, kt\u00f3re mog\u0105 stan\u0105\u0107 Ci na drodze.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">\u2705 <b>Rama KROSS Hexagon 1.0 <\/b>zosta\u0142a wykonana z <b>aluminium performance<\/b>. Stop <b>Aluminium Performance 6061<\/b> to wysoka sztywno\u015b\u0107 i odporno\u015b\u0107 na z\u0142amania, a zarazem lekko\u015b\u0107 typow\u0105 dla aluminium.. Ten specjalny stop <b>aluminium performance 6061<\/b>, zapewnia rowerowi sztywno\u015b\u0107 oraz odporno\u015b\u0107 na przeci\u0105\u017cenia oraz z\u0142amania. Jednocze\u015bnie, jest to stosunkowo lekki materia\u0142, kt\u00f3ry mo\u017ce zaskoczy\u0107 niejednego rowerzyst\u0119 swoimi w\u0142a\u015bciwo\u015bciami. <b>Rama jest malowana proszkowo<\/b>, co przek\u0142ada si\u0119 na trwa\u0142o\u015b\u0107 malowania oraz jego odporno\u015b\u0107 na uszkodzenia mechaniczne.<\/p>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:886px;max-height:552px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk\" srcset=\"https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk 360w,https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk 720w,https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk 886w,https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk 886w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"886px\" alt=\"Rower g\u00f3rski Kross Hexagon 1.0 26 XS(14&amp;quot;) niebieski\/srebrny po\u0142ysk\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:343px;max-height:350px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11717b\/01c9f39146f0942a9f4c27d26fd8\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Kod-producenta-KRHE1Z26X14M006763\" srcset=\"https:\/\/a.allegroimg.com\/original\/11717b\/01c9f39146f0942a9f4c27d26fd8\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Kod-producenta-KRHE1Z26X14M006763 343w,https:\/\/a.allegroimg.com\/original\/11717b\/01c9f39146f0942a9f4c27d26fd8\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Kod-producenta-KRHE1Z26X14M006763 343w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"343px\" alt=\"Rower g\u00f3rski Kross Hexagon 1.0 26 XS(14&amp;quot;) niebieski\/srebrny po\u0142ysk Kod producenta KRHE1Z26X14M006763\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\"><b>\u2705 KROSS Hexagon 1.0<\/b> to tak\u017ce dow\u00f3d na to, \u017ce <b>26 calowe ko\u0142a<\/b> wci\u0105\u017c maj\u0105 si\u0119 dobrze i odnajduj\u0105 si\u0119 we wsp\u00f3\u0142czesnym \u015bwiecie zdominowanych przez dwudziestodziewi\u0119ciocalowce. Wyposa\u017cone zosta\u0142y w <b>opony Wanda o szeroko\u015bci 2,1 cala.<\/b> Taka szeroko\u015b\u0107 opony pozwoli Ci poje\u017adzi\u0107 po lesie oraz nie spowolni\u0105 Ci\u0119 na miejskim asfalcie.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">\u2139\ufe0f SPECYFIKACJA:<\/h3>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">\u27a1\ufe0f Rama i widelec<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>MATERIA\u0141 RAMY:<\/b> ALUMINIUM<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>WIDELEC:<\/b> ZOOM FORGO565<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>SKOK WIDELCA:<\/b> 80MM<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>TYLNY AMORTYZATOR:<\/b> BRAK<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>SKOK TYLNEGO AMORTYZATORA:<\/b> BRAK<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>WYKO\u0143CZENIE LAKIERU:<\/b> PO\u0141YSK<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>KOLOR RAMY:<\/b> NIEBIESKI<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">\u27a1\ufe0f Nap\u0119d<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>PRZERZUTKA PRZ\u00d3D:<\/b> SHIMANO TOURNEY<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>PRZERZUTKA TY\u0141:<\/b> SHIMANO TOURNEY TX800<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>MANETKI:<\/b> SHIMANO TOURNEY REVOSHIFT RS36<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>KORBA:<\/b> WHEEL TOP TCSH4-CFPG<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>KASETA \/ WOLNOBIEG:<\/b> SHIMANO TOURNEY MF-TZ500<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>ZAKRES KASETY\/WOLNOBIEGU:<\/b> 14-28T<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>ILO\u015a\u0106 PRZE\u0141O\u017bE\u0143:<\/b> 21<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>SUPORT:<\/b> FP-B902<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>\u0141A\u0143CUCH:<\/b> YBN S50<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">\u27a1\ufe0f Ko\u0142a<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>PIASTA PRZ\u00d3D:<\/b> GULI GL-B01F<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>PIASTA TY\u0141:<\/b> GULI GL-B01R<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>OBR\u0118CZE:<\/b> KROSS ALUMINIUM 559X19<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>OPONY:<\/b> WANDA P1255 26X2,1<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">\u27a1\ufe0f Hamulce<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>HAMULEC PRZ\u00d3D:<\/b> V-BRAKE<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>HAMULEC TY\u0141:<\/b> V-BRAKE<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>D\u0179WIGNIE HAMULCA:<\/b> ALUMINIUM<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>TARCZE HAMULCOWE:<\/b> BRAK<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>TARCZE HAMULCOWE TY\u0141:<\/b> BRAK<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">\u27a1\ufe0f Komponenty<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>SIOD\u0141O:<\/b> KROSS<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>STERY:<\/b> FP-H863 O1-1\/8&#8243;<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>CHWYTY:<\/b> HERMANS<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>PEDA\u0141Y:<\/b> TWORZYWO<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">\u27a1\ufe0f Informacje dodatkowe<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>WAGA [KG]:<\/b> M &#8211; 13,7<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">\u2757\ufe0f Producent zastrzega sobie zmiany w specyfikacji<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h2>Po wyj\u0119ciu z kartonu do przykr\u0119cenia pozostaj\u0105: kierownica, siode\u0142ko, przednie ko\u0142o oraz peda\u0142y.<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1525px;max-height:1146px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11fbed\/91447ebd472fbb018167cdf71d95\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Rozmiar-ramy-14-cali\" srcset=\"https:\/\/a.allegroimg.com\/original\/11fbed\/91447ebd472fbb018167cdf71d95\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Rozmiar-ramy-14-cali 360w,https:\/\/a.allegroimg.com\/original\/11fbed\/91447ebd472fbb018167cdf71d95\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Rozmiar-ramy-14-cali 720w,https:\/\/a.allegroimg.com\/original\/11fbed\/91447ebd472fbb018167cdf71d95\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Rozmiar-ramy-14-cali 1024w,https:\/\/a.allegroimg.com\/original\/11fbed\/91447ebd472fbb018167cdf71d95\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Rozmiar-ramy-14-cali 1440w,https:\/\/a.allegroimg.com\/original\/11fbed\/91447ebd472fbb018167cdf71d95\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Rozmiar-ramy-14-cali 1525w\" sizes=\"100vw\" width=\"1525px\" alt=\"Rower g\u00f3rski Kross Hexagon 1.0 26 XS(14&amp;quot;) niebieski\/srebrny po\u0142ysk Rozmiar ramy 14 cali\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1539px;max-height:939px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11b225\/e1425bf74379b244854cbd7dc445\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Rozmiar-kola-26\" srcset=\"https:\/\/a.allegroimg.com\/original\/11b225\/e1425bf74379b244854cbd7dc445\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Rozmiar-kola-26 360w,https:\/\/a.allegroimg.com\/original\/11b225\/e1425bf74379b244854cbd7dc445\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Rozmiar-kola-26 720w,https:\/\/a.allegroimg.com\/original\/11b225\/e1425bf74379b244854cbd7dc445\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Rozmiar-kola-26 1024w,https:\/\/a.allegroimg.com\/original\/11b225\/e1425bf74379b244854cbd7dc445\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Rozmiar-kola-26 1440w,https:\/\/a.allegroimg.com\/original\/11b225\/e1425bf74379b244854cbd7dc445\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk-Rozmiar-kola-26 1539w\" sizes=\"100vw\" width=\"1539px\" alt=\"Rower g\u00f3rski Kross Hexagon 1.0 26 XS(14&amp;quot;) niebieski\/srebrny po\u0142ysk Rozmiar ko\u0142a (&quot;) 26\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:886px;max-height:552px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk\" srcset=\"https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk 360w,https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk 720w,https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk 886w,https:\/\/a.allegroimg.com\/original\/111501\/9276b0cd4838a66b13a74b3d0f30\/Rower-gorski-Kross-Hexagon-1-0-26-XS-14-niebieski-srebrny-polysk 886w\" sizes=\"100vw\" width=\"886px\" alt=\"Rower g\u00f3rski Kross Hexagon 1.0 26 XS(14&amp;quot;) niebieski\/srebrny po\u0142ysk\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n","protected":false},"excerpt":{"rendered":"<p>Rower g\u00f3rski Kross Hexagon 1.0 26 XS(14&quot;) niebieski\/srebrny po\u0142ysk<\/p>\n<p>\u2705 Kross jest liderem sprzeda\u017cy rower\u00f3w w Polsce. W sezonie 2022 sprzeda\u017c rower\u00f3w wzros\u0142a a\u017c o 21%. Cechuje go pe\u0142en profesjonalizm i wysoka jako\u015b\u0107 wykonania. Kross w swojej kolekcji posiada rowery do r\u00f3\u017cnych zastosowa\u0144: g\u00f3rskich, szosowych, elektrycznych, turystycznych, miejskich i dzieci\u0119cych.<\/p>\n<p>\u2705 SHIMANO jest najwi\u0119ksz\u0105 na \u015bwiecie firm\u0105 produkuj\u0105c\u0105 cz\u0119\u015bci rowerowe. To najbardziej znana i ceniona marka na rynku, a jej komponenty s\u0105 wykorzystywane w wi\u0119kszo\u015bci rower\u00f3w.<\/p>\n","protected":false},"featured_media":14537,"template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[692],"product_cat":[728,688,687,732],"product_tag":[],"class_list":{"0":"post-14536","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-kross","7":"product_cat-mtb-gorskie","8":"product_cat-rowery","9":"product_cat-rowery-i-akcesoria","10":"product_cat-rowery-mtb-gorskie-26-cali","12":"first","13":"instock","14":"sale","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"uagb_featured_image_src":{"full":["https:\/\/kelzavo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14536.jpg",886,552,false],"thumbnail":["https:\/\/kelzavo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14536-150x150.jpg",150,150,true],"medium":["https:\/\/kelzavo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14536-300x187.jpg",300,187,true],"medium_large":["https:\/\/kelzavo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14536-768x478.jpg",768,478,true],"large":["https:\/\/kelzavo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14536.jpg",886,552,false],"1536x1536":["https:\/\/kelzavo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14536.jpg",886,552,false],"2048x2048":["https:\/\/kelzavo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14536.jpg",886,552,false],"woocommerce_thumbnail":["https:\/\/kelzavo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14536-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/kelzavo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14536-600x374.jpg",600,374,true],"woocommerce_gallery_thumbnail":["https:\/\/kelzavo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14536-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/kelzavo.shop\/ro64\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Rower g\u00f3rski Kross Hexagon 1.0 26 XS(14&quot;) niebieski\/srebrny po\u0142ysk \u2705 Kross jest liderem sprzeda\u017cy rower\u00f3w w Polsce. W sezonie 2022 sprzeda\u017c rower\u00f3w wzros\u0142a a\u017c o 21%. Cechuje go pe\u0142en profesjonalizm i wysoka jako\u015b\u0107 wykonania. Kross w swojej kolekcji posiada rowery do r\u00f3\u017cnych zastosowa\u0144: g\u00f3rskich, szosowych, elektrycznych, turystycznych, miejskich i dzieci\u0119cych. \u2705 SHIMANO jest najwi\u0119ksz\u0105 na&hellip;","_links":{"self":[{"href":"https:\/\/kelzavo.shop\/ro64\/wp-json\/wp\/v2\/product\/14536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kelzavo.shop\/ro64\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kelzavo.shop\/ro64\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kelzavo.shop\/ro64\/wp-json\/wp\/v2\/media\/14537"}],"wp:attachment":[{"href":"https:\/\/kelzavo.shop\/ro64\/wp-json\/wp\/v2\/media?parent=14536"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kelzavo.shop\/ro64\/wp-json\/wp\/v2\/product_brand?post=14536"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kelzavo.shop\/ro64\/wp-json\/wp\/v2\/product_cat?post=14536"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kelzavo.shop\/ro64\/wp-json\/wp\/v2\/product_tag?post=14536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}